{"id":390113,"date":"2024-02-28T09:22:03","date_gmt":"2024-02-28T04:22:03","guid":{"rendered":"https:\/\/leadpakistan.com.pk\/news\/?p=390113"},"modified":"2024-02-28T09:22:03","modified_gmt":"2024-02-28T04:22:03","slug":"who-expresses-concern-over-anticipated-israeli-assault-on-rafah","status":"publish","type":"post","link":"https:\/\/leadpakistan.com.pk\/news\/who-expresses-concern-over-anticipated-israeli-assault-on-rafah\/","title":{"rendered":"WHO expresses concern over anticipated Israeli assault on Rafah"},"content":{"rendered":"<p> Rafah<br \/>\nThe World Health Organization has expressed concern over an anticipated Israeli assault on Rafah.<br \/>\nIn a social media post, WHO chief Tedros Adhanom Ghebreyesus has expressed apprehensions of a full-scale incursion into Rafah, where over a million people are sheltering in crowded conditions, lacking food, water, medicine.<br \/>\nHe asked Israel to consider the humanitarian implications and reiterated his call for a ceasefire and peace to prevail.<br \/>\nThe President of the United States Joe Biden says Israel is ready to halt its attacks on Gaza during holy month of Ramzan.<br \/>\nIn a statement, he expressed hope that the ceasefire deal will be signed next week.<br \/>\nOn the other hand, the martyrdom toll has risen to over twenty nine thousand and eight hundred since October last year.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Rafah The World Health Organization has expressed concern over an anticipated Israeli assault on Rafah. In a social media post, WHO chief Tedros Adhanom Ghebreyesus has expressed apprehensions of a full-scale incursion into Rafah, where over a million people are sheltering in crowded conditions, lacking food, water, medicine. He asked Israel to consider the humanitarian [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":{"0":"post-390113","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-world"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>WHO expresses concern over anticipated Israeli assault on Rafah<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/leadpakistan.com.pk\/news\/who-expresses-concern-over-anticipated-israeli-assault-on-rafah\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"WHO expresses concern over anticipated Israeli assault on Rafah\" \/>\n<meta property=\"og:description\" content=\"Rafah The World Health Organization has expressed concern over an anticipated Israeli assault on Rafah. In a social media post, WHO chief Tedros Adhanom Ghebreyesus has expressed apprehensions of a full-scale incursion into Rafah, where over a million people are sheltering in crowded conditions, lacking food, water, medicine. He asked Israel to consider the humanitarian [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/leadpakistan.com.pk\/news\/who-expresses-concern-over-anticipated-israeli-assault-on-rafah\/\" \/>\n<meta property=\"og:site_name\" content=\"Daily Lead Pakistan\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/DailyLeadPak\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-28T04:22:03+00:00\" \/>\n<meta name=\"author\" content=\"Web Desk\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@DailyLeadPak\" \/>\n<meta name=\"twitter:site\" content=\"@DailyLeadPak\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Web Desk\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/leadpakistan.com.pk\\\/news\\\/who-expresses-concern-over-anticipated-israeli-assault-on-rafah\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/leadpakistan.com.pk\\\/news\\\/who-expresses-concern-over-anticipated-israeli-assault-on-rafah\\\/\"},\"author\":{\"name\":\"Web Desk\",\"@id\":\"https:\\\/\\\/leadpakistan.com.pk\\\/news\\\/#\\\/schema\\\/person\\\/6ef8309590ff620a99ce35559f54fd62\"},\"headline\":\"WHO expresses concern over anticipated Israeli assault on Rafah\",\"datePublished\":\"2024-02-28T04:22:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/leadpakistan.com.pk\\\/news\\\/who-expresses-concern-over-anticipated-israeli-assault-on-rafah\\\/\"},\"wordCount\":135,\"publisher\":{\"@id\":\"https:\\\/\\\/leadpakistan.com.pk\\\/news\\\/#organization\"},\"articleSection\":[\"World\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/leadpakistan.com.pk\\\/news\\\/who-expresses-concern-over-anticipated-israeli-assault-on-rafah\\\/\",\"url\":\"https:\\\/\\\/leadpakistan.com.pk\\\/news\\\/who-expresses-concern-over-anticipated-israeli-assault-on-rafah\\\/\",\"name\":\"WHO expresses concern over anticipated Israeli assault on Rafah\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/leadpakistan.com.pk\\\/news\\\/#website\"},\"datePublished\":\"2024-02-28T04:22:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/leadpakistan.com.pk\\\/news\\\/who-expresses-concern-over-anticipated-israeli-assault-on-rafah\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/leadpakistan.com.pk\\\/news\\\/who-expresses-concern-over-anticipated-israeli-assault-on-rafah\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/leadpakistan.com.pk\\\/news\\\/who-expresses-concern-over-anticipated-israeli-assault-on-rafah\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/leadpakistan.com.pk\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"WHO expresses concern over anticipated Israeli assault on Rafah\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/leadpakistan.com.pk\\\/news\\\/#website\",\"url\":\"https:\\\/\\\/leadpakistan.com.pk\\\/news\\\/\",\"name\":\"Daily Lead Pakistan\",\"description\":\"Daily Lead Pakistan\",\"publisher\":{\"@id\":\"https:\\\/\\\/leadpakistan.com.pk\\\/news\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/leadpakistan.com.pk\\\/news\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/leadpakistan.com.pk\\\/news\\\/#organization\",\"name\":\"Daily lead Pakistan\",\"url\":\"https:\\\/\\\/leadpakistan.com.pk\\\/news\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/leadpakistan.com.pk\\\/news\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/leadpakistan.com.pk\\\/news\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/logo3.jpg\",\"contentUrl\":\"https:\\\/\\\/leadpakistan.com.pk\\\/news\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/logo3.jpg\",\"width\":1000,\"height\":154,\"caption\":\"Daily lead Pakistan\"},\"image\":{\"@id\":\"https:\\\/\\\/leadpakistan.com.pk\\\/news\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/DailyLeadPak\\\/\",\"https:\\\/\\\/x.com\\\/DailyLeadPak\",\"https:\\\/\\\/instagram.com\\\/DailyLeadPak\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/leadpakistan.com.pk\\\/news\\\/#\\\/schema\\\/person\\\/6ef8309590ff620a99ce35559f54fd62\",\"name\":\"Web Desk\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/41f05ebf0a510062a26cf1d9e662155a6901c6733aa66a6c0f61daea3d680dc7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/41f05ebf0a510062a26cf1d9e662155a6901c6733aa66a6c0f61daea3d680dc7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/41f05ebf0a510062a26cf1d9e662155a6901c6733aa66a6c0f61daea3d680dc7?s=96&d=mm&r=g\",\"caption\":\"Web Desk\"},\"url\":\"https:\\\/\\\/leadpakistan.com.pk\\\/news\\\/author\\\/edt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"WHO expresses concern over anticipated Israeli assault on Rafah","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/leadpakistan.com.pk\/news\/who-expresses-concern-over-anticipated-israeli-assault-on-rafah\/","og_locale":"en_US","og_type":"article","og_title":"WHO expresses concern over anticipated Israeli assault on Rafah","og_description":"Rafah The World Health Organization has expressed concern over an anticipated Israeli assault on Rafah. In a social media post, WHO chief Tedros Adhanom Ghebreyesus has expressed apprehensions of a full-scale incursion into Rafah, where over a million people are sheltering in crowded conditions, lacking food, water, medicine. He asked Israel to consider the humanitarian [&hellip;]","og_url":"https:\/\/leadpakistan.com.pk\/news\/who-expresses-concern-over-anticipated-israeli-assault-on-rafah\/","og_site_name":"Daily Lead Pakistan","article_publisher":"https:\/\/www.facebook.com\/DailyLeadPak\/","article_published_time":"2024-02-28T04:22:03+00:00","author":"Web Desk","twitter_card":"summary_large_image","twitter_creator":"@DailyLeadPak","twitter_site":"@DailyLeadPak","twitter_misc":{"Written by":"Web Desk","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/leadpakistan.com.pk\/news\/who-expresses-concern-over-anticipated-israeli-assault-on-rafah\/#article","isPartOf":{"@id":"https:\/\/leadpakistan.com.pk\/news\/who-expresses-concern-over-anticipated-israeli-assault-on-rafah\/"},"author":{"name":"Web Desk","@id":"https:\/\/leadpakistan.com.pk\/news\/#\/schema\/person\/6ef8309590ff620a99ce35559f54fd62"},"headline":"WHO expresses concern over anticipated Israeli assault on Rafah","datePublished":"2024-02-28T04:22:03+00:00","mainEntityOfPage":{"@id":"https:\/\/leadpakistan.com.pk\/news\/who-expresses-concern-over-anticipated-israeli-assault-on-rafah\/"},"wordCount":135,"publisher":{"@id":"https:\/\/leadpakistan.com.pk\/news\/#organization"},"articleSection":["World"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/leadpakistan.com.pk\/news\/who-expresses-concern-over-anticipated-israeli-assault-on-rafah\/","url":"https:\/\/leadpakistan.com.pk\/news\/who-expresses-concern-over-anticipated-israeli-assault-on-rafah\/","name":"WHO expresses concern over anticipated Israeli assault on Rafah","isPartOf":{"@id":"https:\/\/leadpakistan.com.pk\/news\/#website"},"datePublished":"2024-02-28T04:22:03+00:00","breadcrumb":{"@id":"https:\/\/leadpakistan.com.pk\/news\/who-expresses-concern-over-anticipated-israeli-assault-on-rafah\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/leadpakistan.com.pk\/news\/who-expresses-concern-over-anticipated-israeli-assault-on-rafah\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/leadpakistan.com.pk\/news\/who-expresses-concern-over-anticipated-israeli-assault-on-rafah\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/leadpakistan.com.pk\/news\/"},{"@type":"ListItem","position":2,"name":"WHO expresses concern over anticipated Israeli assault on Rafah"}]},{"@type":"WebSite","@id":"https:\/\/leadpakistan.com.pk\/news\/#website","url":"https:\/\/leadpakistan.com.pk\/news\/","name":"Daily Lead Pakistan","description":"Daily Lead Pakistan","publisher":{"@id":"https:\/\/leadpakistan.com.pk\/news\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/leadpakistan.com.pk\/news\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/leadpakistan.com.pk\/news\/#organization","name":"Daily lead Pakistan","url":"https:\/\/leadpakistan.com.pk\/news\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/leadpakistan.com.pk\/news\/#\/schema\/logo\/image\/","url":"https:\/\/leadpakistan.com.pk\/news\/wp-content\/uploads\/2022\/04\/logo3.jpg","contentUrl":"https:\/\/leadpakistan.com.pk\/news\/wp-content\/uploads\/2022\/04\/logo3.jpg","width":1000,"height":154,"caption":"Daily lead Pakistan"},"image":{"@id":"https:\/\/leadpakistan.com.pk\/news\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/DailyLeadPak\/","https:\/\/x.com\/DailyLeadPak","https:\/\/instagram.com\/DailyLeadPak\/"]},{"@type":"Person","@id":"https:\/\/leadpakistan.com.pk\/news\/#\/schema\/person\/6ef8309590ff620a99ce35559f54fd62","name":"Web Desk","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/41f05ebf0a510062a26cf1d9e662155a6901c6733aa66a6c0f61daea3d680dc7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/41f05ebf0a510062a26cf1d9e662155a6901c6733aa66a6c0f61daea3d680dc7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/41f05ebf0a510062a26cf1d9e662155a6901c6733aa66a6c0f61daea3d680dc7?s=96&d=mm&r=g","caption":"Web Desk"},"url":"https:\/\/leadpakistan.com.pk\/news\/author\/edt\/"}]}},"_links":{"self":[{"href":"https:\/\/leadpakistan.com.pk\/news\/wp-json\/wp\/v2\/posts\/390113","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/leadpakistan.com.pk\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/leadpakistan.com.pk\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/leadpakistan.com.pk\/news\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/leadpakistan.com.pk\/news\/wp-json\/wp\/v2\/comments?post=390113"}],"version-history":[{"count":1,"href":"https:\/\/leadpakistan.com.pk\/news\/wp-json\/wp\/v2\/posts\/390113\/revisions"}],"predecessor-version":[{"id":390125,"href":"https:\/\/leadpakistan.com.pk\/news\/wp-json\/wp\/v2\/posts\/390113\/revisions\/390125"}],"wp:attachment":[{"href":"https:\/\/leadpakistan.com.pk\/news\/wp-json\/wp\/v2\/media?parent=390113"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/leadpakistan.com.pk\/news\/wp-json\/wp\/v2\/categories?post=390113"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/leadpakistan.com.pk\/news\/wp-json\/wp\/v2\/tags?post=390113"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}