{"id":544877,"date":"2026-05-06T00:19:36","date_gmt":"2026-05-05T19:19:36","guid":{"rendered":"https:\/\/leadpakistan.com.pk\/news\/?p=544877"},"modified":"2026-05-06T00:19:36","modified_gmt":"2026-05-05T19:19:36","slug":"sho-killed-in-firing-by-police-in-shikarpur","status":"publish","type":"post","link":"https:\/\/leadpakistan.com.pk\/news\/sho-killed-in-firing-by-police-in-shikarpur\/","title":{"rendered":"SHO killed in firing by police in Shikarpur"},"content":{"rendered":"<p>SHIKARPUR: SHO travelling in car has been killed in firing by police personnel from his own force near Lakhi Ghulam Shah in Shikarpur. According to media report Lakhi Ghulam Shah police intercepted private car and signaled it to stop but it did not stop and police opened fire on it. The SHO who was critically injured in firing was taken to hospital in precarious condition but he succumbed to injuries. Ali Hassan was appointed as SHO in police station Ghulam Shah. Police said an inquiry committee under SP Shikarpur has been constituted to investigate the matter. Inquiry committee has been directed to present report within 24 hours. Online<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SHIKARPUR: SHO travelling in car has been killed in firing by police personnel from his own force near Lakhi Ghulam Shah in Shikarpur. According to media report Lakhi Ghulam Shah police intercepted private car and signaled it to stop but it did not stop and police opened fire on it. The SHO who was critically [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":{"0":"post-544877","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-national"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SHO killed in firing by police in Shikarpur<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/leadpakistan.com.pk\/news\/sho-killed-in-firing-by-police-in-shikarpur\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SHO killed in firing by police in Shikarpur\" \/>\n<meta property=\"og:description\" content=\"SHIKARPUR: SHO travelling in car has been killed in firing by police personnel from his own force near Lakhi Ghulam Shah in Shikarpur. According to media report Lakhi Ghulam Shah police intercepted private car and signaled it to stop but it did not stop and police opened fire on it. The SHO who was critically [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/leadpakistan.com.pk\/news\/sho-killed-in-firing-by-police-in-shikarpur\/\" \/>\n<meta property=\"og:site_name\" content=\"Daily Lead Pakistan\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/DailyLeadPak\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-05T19:19:36+00:00\" \/>\n<meta name=\"author\" content=\"Web Desk\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@DailyLeadPak\" \/>\n<meta name=\"twitter:site\" content=\"@DailyLeadPak\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Web Desk\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/leadpakistan.com.pk\\\/news\\\/sho-killed-in-firing-by-police-in-shikarpur\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/leadpakistan.com.pk\\\/news\\\/sho-killed-in-firing-by-police-in-shikarpur\\\/\"},\"author\":{\"name\":\"Web Desk\",\"@id\":\"https:\\\/\\\/leadpakistan.com.pk\\\/news\\\/#\\\/schema\\\/person\\\/6ef8309590ff620a99ce35559f54fd62\"},\"headline\":\"SHO killed in firing by police in Shikarpur\",\"datePublished\":\"2026-05-05T19:19:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/leadpakistan.com.pk\\\/news\\\/sho-killed-in-firing-by-police-in-shikarpur\\\/\"},\"wordCount\":115,\"publisher\":{\"@id\":\"https:\\\/\\\/leadpakistan.com.pk\\\/news\\\/#organization\"},\"articleSection\":[\"National\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/leadpakistan.com.pk\\\/news\\\/sho-killed-in-firing-by-police-in-shikarpur\\\/\",\"url\":\"https:\\\/\\\/leadpakistan.com.pk\\\/news\\\/sho-killed-in-firing-by-police-in-shikarpur\\\/\",\"name\":\"SHO killed in firing by police in Shikarpur\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/leadpakistan.com.pk\\\/news\\\/#website\"},\"datePublished\":\"2026-05-05T19:19:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/leadpakistan.com.pk\\\/news\\\/sho-killed-in-firing-by-police-in-shikarpur\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/leadpakistan.com.pk\\\/news\\\/sho-killed-in-firing-by-police-in-shikarpur\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/leadpakistan.com.pk\\\/news\\\/sho-killed-in-firing-by-police-in-shikarpur\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/leadpakistan.com.pk\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SHO killed in firing by police in Shikarpur\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/leadpakistan.com.pk\\\/news\\\/#website\",\"url\":\"https:\\\/\\\/leadpakistan.com.pk\\\/news\\\/\",\"name\":\"Daily Lead Pakistan\",\"description\":\"Daily Lead Pakistan\",\"publisher\":{\"@id\":\"https:\\\/\\\/leadpakistan.com.pk\\\/news\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/leadpakistan.com.pk\\\/news\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/leadpakistan.com.pk\\\/news\\\/#organization\",\"name\":\"Daily lead Pakistan\",\"url\":\"https:\\\/\\\/leadpakistan.com.pk\\\/news\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/leadpakistan.com.pk\\\/news\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/leadpakistan.com.pk\\\/news\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/logo3.jpg\",\"contentUrl\":\"https:\\\/\\\/leadpakistan.com.pk\\\/news\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/logo3.jpg\",\"width\":1000,\"height\":154,\"caption\":\"Daily lead Pakistan\"},\"image\":{\"@id\":\"https:\\\/\\\/leadpakistan.com.pk\\\/news\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/DailyLeadPak\\\/\",\"https:\\\/\\\/x.com\\\/DailyLeadPak\",\"https:\\\/\\\/instagram.com\\\/DailyLeadPak\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/leadpakistan.com.pk\\\/news\\\/#\\\/schema\\\/person\\\/6ef8309590ff620a99ce35559f54fd62\",\"name\":\"Web Desk\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/41f05ebf0a510062a26cf1d9e662155a6901c6733aa66a6c0f61daea3d680dc7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/41f05ebf0a510062a26cf1d9e662155a6901c6733aa66a6c0f61daea3d680dc7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/41f05ebf0a510062a26cf1d9e662155a6901c6733aa66a6c0f61daea3d680dc7?s=96&d=mm&r=g\",\"caption\":\"Web Desk\"},\"url\":\"https:\\\/\\\/leadpakistan.com.pk\\\/news\\\/author\\\/edt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SHO killed in firing by police in Shikarpur","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/leadpakistan.com.pk\/news\/sho-killed-in-firing-by-police-in-shikarpur\/","og_locale":"en_US","og_type":"article","og_title":"SHO killed in firing by police in Shikarpur","og_description":"SHIKARPUR: SHO travelling in car has been killed in firing by police personnel from his own force near Lakhi Ghulam Shah in Shikarpur. According to media report Lakhi Ghulam Shah police intercepted private car and signaled it to stop but it did not stop and police opened fire on it. The SHO who was critically [&hellip;]","og_url":"https:\/\/leadpakistan.com.pk\/news\/sho-killed-in-firing-by-police-in-shikarpur\/","og_site_name":"Daily Lead Pakistan","article_publisher":"https:\/\/www.facebook.com\/DailyLeadPak\/","article_published_time":"2026-05-05T19:19:36+00:00","author":"Web Desk","twitter_card":"summary_large_image","twitter_creator":"@DailyLeadPak","twitter_site":"@DailyLeadPak","twitter_misc":{"Written by":"Web Desk","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/leadpakistan.com.pk\/news\/sho-killed-in-firing-by-police-in-shikarpur\/#article","isPartOf":{"@id":"https:\/\/leadpakistan.com.pk\/news\/sho-killed-in-firing-by-police-in-shikarpur\/"},"author":{"name":"Web Desk","@id":"https:\/\/leadpakistan.com.pk\/news\/#\/schema\/person\/6ef8309590ff620a99ce35559f54fd62"},"headline":"SHO killed in firing by police in Shikarpur","datePublished":"2026-05-05T19:19:36+00:00","mainEntityOfPage":{"@id":"https:\/\/leadpakistan.com.pk\/news\/sho-killed-in-firing-by-police-in-shikarpur\/"},"wordCount":115,"publisher":{"@id":"https:\/\/leadpakistan.com.pk\/news\/#organization"},"articleSection":["National"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/leadpakistan.com.pk\/news\/sho-killed-in-firing-by-police-in-shikarpur\/","url":"https:\/\/leadpakistan.com.pk\/news\/sho-killed-in-firing-by-police-in-shikarpur\/","name":"SHO killed in firing by police in Shikarpur","isPartOf":{"@id":"https:\/\/leadpakistan.com.pk\/news\/#website"},"datePublished":"2026-05-05T19:19:36+00:00","breadcrumb":{"@id":"https:\/\/leadpakistan.com.pk\/news\/sho-killed-in-firing-by-police-in-shikarpur\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/leadpakistan.com.pk\/news\/sho-killed-in-firing-by-police-in-shikarpur\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/leadpakistan.com.pk\/news\/sho-killed-in-firing-by-police-in-shikarpur\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/leadpakistan.com.pk\/news\/"},{"@type":"ListItem","position":2,"name":"SHO killed in firing by police in Shikarpur"}]},{"@type":"WebSite","@id":"https:\/\/leadpakistan.com.pk\/news\/#website","url":"https:\/\/leadpakistan.com.pk\/news\/","name":"Daily Lead Pakistan","description":"Daily Lead Pakistan","publisher":{"@id":"https:\/\/leadpakistan.com.pk\/news\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/leadpakistan.com.pk\/news\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/leadpakistan.com.pk\/news\/#organization","name":"Daily lead Pakistan","url":"https:\/\/leadpakistan.com.pk\/news\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/leadpakistan.com.pk\/news\/#\/schema\/logo\/image\/","url":"https:\/\/leadpakistan.com.pk\/news\/wp-content\/uploads\/2022\/04\/logo3.jpg","contentUrl":"https:\/\/leadpakistan.com.pk\/news\/wp-content\/uploads\/2022\/04\/logo3.jpg","width":1000,"height":154,"caption":"Daily lead Pakistan"},"image":{"@id":"https:\/\/leadpakistan.com.pk\/news\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/DailyLeadPak\/","https:\/\/x.com\/DailyLeadPak","https:\/\/instagram.com\/DailyLeadPak\/"]},{"@type":"Person","@id":"https:\/\/leadpakistan.com.pk\/news\/#\/schema\/person\/6ef8309590ff620a99ce35559f54fd62","name":"Web Desk","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/41f05ebf0a510062a26cf1d9e662155a6901c6733aa66a6c0f61daea3d680dc7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/41f05ebf0a510062a26cf1d9e662155a6901c6733aa66a6c0f61daea3d680dc7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/41f05ebf0a510062a26cf1d9e662155a6901c6733aa66a6c0f61daea3d680dc7?s=96&d=mm&r=g","caption":"Web Desk"},"url":"https:\/\/leadpakistan.com.pk\/news\/author\/edt\/"}]}},"_links":{"self":[{"href":"https:\/\/leadpakistan.com.pk\/news\/wp-json\/wp\/v2\/posts\/544877","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/leadpakistan.com.pk\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/leadpakistan.com.pk\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/leadpakistan.com.pk\/news\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/leadpakistan.com.pk\/news\/wp-json\/wp\/v2\/comments?post=544877"}],"version-history":[{"count":1,"href":"https:\/\/leadpakistan.com.pk\/news\/wp-json\/wp\/v2\/posts\/544877\/revisions"}],"predecessor-version":[{"id":544885,"href":"https:\/\/leadpakistan.com.pk\/news\/wp-json\/wp\/v2\/posts\/544877\/revisions\/544885"}],"wp:attachment":[{"href":"https:\/\/leadpakistan.com.pk\/news\/wp-json\/wp\/v2\/media?parent=544877"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/leadpakistan.com.pk\/news\/wp-json\/wp\/v2\/categories?post=544877"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/leadpakistan.com.pk\/news\/wp-json\/wp\/v2\/tags?post=544877"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}