{"id":556388,"date":"2026-07-15T15:13:37","date_gmt":"2026-07-15T10:13:37","guid":{"rendered":"https:\/\/leadpakistan.com.pk\/news\/?p=556388"},"modified":"2026-07-15T15:13:37","modified_gmt":"2026-07-15T10:13:37","slug":"igp-rizvi-directs-capital-patrol-unit-to-enhance-vigilance-public-service","status":"publish","type":"post","link":"https:\/\/leadpakistan.com.pk\/news\/igp-rizvi-directs-capital-patrol-unit-to-enhance-vigilance-public-service\/","title":{"rendered":"IGP Rizvi directs Capital Patrol Unit to enhance vigilance, public service"},"content":{"rendered":"<p>Inspector General of Police (IGP) Islamabad Syed Ali Nasir Rizvi  briefed officers of the Capital Patrol Unit (CPU), directing them to maintain high standards of discipline, professionalism and public service while performing their duties.<br \/>\nAn official told APP on Wednesday that the IGP issued detailed instructions regarding duty discipline, courteous public dealing, prompt response, effective patrolling and close monitoring of suspicious activities.<br \/>\nRizvi emphasized that the Capital Patrol Unit must remain fully alert to ensure timely assistance to citizens and strengthen preventive policing across the federal capital.<br \/>\n IGP Rizvi also reviewed the overall law and order situation and directed officers to further improve the patrolling system to enhance public safety.<br \/>\nHe instructed personnel to ensure effective enforcement of the law, protect the lives and property of citizens and maintain the highest standards of performance during duty.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Inspector General of Police (IGP) Islamabad Syed Ali Nasir Rizvi briefed officers of the Capital Patrol Unit (CPU), directing them to maintain high standards of discipline, professionalism and public service while performing their duties. An official told APP on Wednesday that the IGP issued detailed instructions regarding duty discipline, courteous public dealing, prompt response, effective [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":556400,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-556388","post","type-post","status-publish","format-standard","has-post-thumbnail","category-national"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>IGP Rizvi directs Capital Patrol Unit to enhance vigilance, public service<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/leadpakistan.com.pk\/news\/igp-rizvi-directs-capital-patrol-unit-to-enhance-vigilance-public-service\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"IGP Rizvi directs Capital Patrol Unit to enhance vigilance, public service\" \/>\n<meta property=\"og:description\" content=\"Inspector General of Police (IGP) Islamabad Syed Ali Nasir Rizvi briefed officers of the Capital Patrol Unit (CPU), directing them to maintain high standards of discipline, professionalism and public service while performing their duties. An official told APP on Wednesday that the IGP issued detailed instructions regarding duty discipline, courteous public dealing, prompt response, effective [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/leadpakistan.com.pk\/news\/igp-rizvi-directs-capital-patrol-unit-to-enhance-vigilance-public-service\/\" \/>\n<meta property=\"og:site_name\" content=\"Daily Lead Pakistan\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/DailyLeadPak\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-15T10:13:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/leadpakistan.com.pk\/news\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-15-at-12.02.02-PM.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1289\" \/>\n\t<meta property=\"og:image:height\" content=\"1007\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Web Desk\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@DailyLeadPak\" \/>\n<meta name=\"twitter:site\" content=\"@DailyLeadPak\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Web Desk\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/leadpakistan.com.pk\\\/news\\\/igp-rizvi-directs-capital-patrol-unit-to-enhance-vigilance-public-service\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/leadpakistan.com.pk\\\/news\\\/igp-rizvi-directs-capital-patrol-unit-to-enhance-vigilance-public-service\\\/\"},\"author\":{\"name\":\"Web Desk\",\"@id\":\"https:\\\/\\\/leadpakistan.com.pk\\\/news\\\/#\\\/schema\\\/person\\\/6ef8309590ff620a99ce35559f54fd62\"},\"headline\":\"IGP Rizvi directs Capital Patrol Unit to enhance vigilance, public service\",\"datePublished\":\"2026-07-15T10:13:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/leadpakistan.com.pk\\\/news\\\/igp-rizvi-directs-capital-patrol-unit-to-enhance-vigilance-public-service\\\/\"},\"wordCount\":147,\"publisher\":{\"@id\":\"https:\\\/\\\/leadpakistan.com.pk\\\/news\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/leadpakistan.com.pk\\\/news\\\/igp-rizvi-directs-capital-patrol-unit-to-enhance-vigilance-public-service\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/leadpakistan.com.pk\\\/news\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/WhatsApp-Image-2026-07-15-at-12.02.02-PM.jpeg\",\"articleSection\":[\"National\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/leadpakistan.com.pk\\\/news\\\/igp-rizvi-directs-capital-patrol-unit-to-enhance-vigilance-public-service\\\/\",\"url\":\"https:\\\/\\\/leadpakistan.com.pk\\\/news\\\/igp-rizvi-directs-capital-patrol-unit-to-enhance-vigilance-public-service\\\/\",\"name\":\"IGP Rizvi directs Capital Patrol Unit to enhance vigilance, public service\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/leadpakistan.com.pk\\\/news\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/leadpakistan.com.pk\\\/news\\\/igp-rizvi-directs-capital-patrol-unit-to-enhance-vigilance-public-service\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/leadpakistan.com.pk\\\/news\\\/igp-rizvi-directs-capital-patrol-unit-to-enhance-vigilance-public-service\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/leadpakistan.com.pk\\\/news\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/WhatsApp-Image-2026-07-15-at-12.02.02-PM.jpeg\",\"datePublished\":\"2026-07-15T10:13:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/leadpakistan.com.pk\\\/news\\\/igp-rizvi-directs-capital-patrol-unit-to-enhance-vigilance-public-service\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/leadpakistan.com.pk\\\/news\\\/igp-rizvi-directs-capital-patrol-unit-to-enhance-vigilance-public-service\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/leadpakistan.com.pk\\\/news\\\/igp-rizvi-directs-capital-patrol-unit-to-enhance-vigilance-public-service\\\/#primaryimage\",\"url\":\"https:\\\/\\\/leadpakistan.com.pk\\\/news\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/WhatsApp-Image-2026-07-15-at-12.02.02-PM.jpeg\",\"contentUrl\":\"https:\\\/\\\/leadpakistan.com.pk\\\/news\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/WhatsApp-Image-2026-07-15-at-12.02.02-PM.jpeg\",\"width\":1289,\"height\":1007},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/leadpakistan.com.pk\\\/news\\\/igp-rizvi-directs-capital-patrol-unit-to-enhance-vigilance-public-service\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/leadpakistan.com.pk\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"IGP Rizvi directs Capital Patrol Unit to enhance vigilance, public service\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/leadpakistan.com.pk\\\/news\\\/#website\",\"url\":\"https:\\\/\\\/leadpakistan.com.pk\\\/news\\\/\",\"name\":\"Daily Lead Pakistan\",\"description\":\"Daily Lead Pakistan\",\"publisher\":{\"@id\":\"https:\\\/\\\/leadpakistan.com.pk\\\/news\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/leadpakistan.com.pk\\\/news\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/leadpakistan.com.pk\\\/news\\\/#organization\",\"name\":\"Daily lead Pakistan\",\"url\":\"https:\\\/\\\/leadpakistan.com.pk\\\/news\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/leadpakistan.com.pk\\\/news\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/leadpakistan.com.pk\\\/news\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/logo3.jpg\",\"contentUrl\":\"https:\\\/\\\/leadpakistan.com.pk\\\/news\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/logo3.jpg\",\"width\":1000,\"height\":154,\"caption\":\"Daily lead Pakistan\"},\"image\":{\"@id\":\"https:\\\/\\\/leadpakistan.com.pk\\\/news\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/DailyLeadPak\\\/\",\"https:\\\/\\\/x.com\\\/DailyLeadPak\",\"https:\\\/\\\/instagram.com\\\/DailyLeadPak\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/leadpakistan.com.pk\\\/news\\\/#\\\/schema\\\/person\\\/6ef8309590ff620a99ce35559f54fd62\",\"name\":\"Web Desk\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/41f05ebf0a510062a26cf1d9e662155a6901c6733aa66a6c0f61daea3d680dc7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/41f05ebf0a510062a26cf1d9e662155a6901c6733aa66a6c0f61daea3d680dc7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/41f05ebf0a510062a26cf1d9e662155a6901c6733aa66a6c0f61daea3d680dc7?s=96&d=mm&r=g\",\"caption\":\"Web Desk\"},\"url\":\"https:\\\/\\\/leadpakistan.com.pk\\\/news\\\/author\\\/edt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"IGP Rizvi directs Capital Patrol Unit to enhance vigilance, public service","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/leadpakistan.com.pk\/news\/igp-rizvi-directs-capital-patrol-unit-to-enhance-vigilance-public-service\/","og_locale":"en_US","og_type":"article","og_title":"IGP Rizvi directs Capital Patrol Unit to enhance vigilance, public service","og_description":"Inspector General of Police (IGP) Islamabad Syed Ali Nasir Rizvi briefed officers of the Capital Patrol Unit (CPU), directing them to maintain high standards of discipline, professionalism and public service while performing their duties. An official told APP on Wednesday that the IGP issued detailed instructions regarding duty discipline, courteous public dealing, prompt response, effective [&hellip;]","og_url":"https:\/\/leadpakistan.com.pk\/news\/igp-rizvi-directs-capital-patrol-unit-to-enhance-vigilance-public-service\/","og_site_name":"Daily Lead Pakistan","article_publisher":"https:\/\/www.facebook.com\/DailyLeadPak\/","article_published_time":"2026-07-15T10:13:37+00:00","og_image":[{"width":1289,"height":1007,"url":"https:\/\/leadpakistan.com.pk\/news\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-15-at-12.02.02-PM.jpeg","type":"image\/jpeg"}],"author":"Web Desk","twitter_card":"summary_large_image","twitter_creator":"@DailyLeadPak","twitter_site":"@DailyLeadPak","twitter_misc":{"Written by":"Web Desk","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/leadpakistan.com.pk\/news\/igp-rizvi-directs-capital-patrol-unit-to-enhance-vigilance-public-service\/#article","isPartOf":{"@id":"https:\/\/leadpakistan.com.pk\/news\/igp-rizvi-directs-capital-patrol-unit-to-enhance-vigilance-public-service\/"},"author":{"name":"Web Desk","@id":"https:\/\/leadpakistan.com.pk\/news\/#\/schema\/person\/6ef8309590ff620a99ce35559f54fd62"},"headline":"IGP Rizvi directs Capital Patrol Unit to enhance vigilance, public service","datePublished":"2026-07-15T10:13:37+00:00","mainEntityOfPage":{"@id":"https:\/\/leadpakistan.com.pk\/news\/igp-rizvi-directs-capital-patrol-unit-to-enhance-vigilance-public-service\/"},"wordCount":147,"publisher":{"@id":"https:\/\/leadpakistan.com.pk\/news\/#organization"},"image":{"@id":"https:\/\/leadpakistan.com.pk\/news\/igp-rizvi-directs-capital-patrol-unit-to-enhance-vigilance-public-service\/#primaryimage"},"thumbnailUrl":"https:\/\/leadpakistan.com.pk\/news\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-15-at-12.02.02-PM.jpeg","articleSection":["National"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/leadpakistan.com.pk\/news\/igp-rizvi-directs-capital-patrol-unit-to-enhance-vigilance-public-service\/","url":"https:\/\/leadpakistan.com.pk\/news\/igp-rizvi-directs-capital-patrol-unit-to-enhance-vigilance-public-service\/","name":"IGP Rizvi directs Capital Patrol Unit to enhance vigilance, public service","isPartOf":{"@id":"https:\/\/leadpakistan.com.pk\/news\/#website"},"primaryImageOfPage":{"@id":"https:\/\/leadpakistan.com.pk\/news\/igp-rizvi-directs-capital-patrol-unit-to-enhance-vigilance-public-service\/#primaryimage"},"image":{"@id":"https:\/\/leadpakistan.com.pk\/news\/igp-rizvi-directs-capital-patrol-unit-to-enhance-vigilance-public-service\/#primaryimage"},"thumbnailUrl":"https:\/\/leadpakistan.com.pk\/news\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-15-at-12.02.02-PM.jpeg","datePublished":"2026-07-15T10:13:37+00:00","breadcrumb":{"@id":"https:\/\/leadpakistan.com.pk\/news\/igp-rizvi-directs-capital-patrol-unit-to-enhance-vigilance-public-service\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/leadpakistan.com.pk\/news\/igp-rizvi-directs-capital-patrol-unit-to-enhance-vigilance-public-service\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/leadpakistan.com.pk\/news\/igp-rizvi-directs-capital-patrol-unit-to-enhance-vigilance-public-service\/#primaryimage","url":"https:\/\/leadpakistan.com.pk\/news\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-15-at-12.02.02-PM.jpeg","contentUrl":"https:\/\/leadpakistan.com.pk\/news\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-15-at-12.02.02-PM.jpeg","width":1289,"height":1007},{"@type":"BreadcrumbList","@id":"https:\/\/leadpakistan.com.pk\/news\/igp-rizvi-directs-capital-patrol-unit-to-enhance-vigilance-public-service\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/leadpakistan.com.pk\/news\/"},{"@type":"ListItem","position":2,"name":"IGP Rizvi directs Capital Patrol Unit to enhance vigilance, public service"}]},{"@type":"WebSite","@id":"https:\/\/leadpakistan.com.pk\/news\/#website","url":"https:\/\/leadpakistan.com.pk\/news\/","name":"Daily Lead Pakistan","description":"Daily Lead Pakistan","publisher":{"@id":"https:\/\/leadpakistan.com.pk\/news\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/leadpakistan.com.pk\/news\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/leadpakistan.com.pk\/news\/#organization","name":"Daily lead Pakistan","url":"https:\/\/leadpakistan.com.pk\/news\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/leadpakistan.com.pk\/news\/#\/schema\/logo\/image\/","url":"https:\/\/leadpakistan.com.pk\/news\/wp-content\/uploads\/2022\/04\/logo3.jpg","contentUrl":"https:\/\/leadpakistan.com.pk\/news\/wp-content\/uploads\/2022\/04\/logo3.jpg","width":1000,"height":154,"caption":"Daily lead Pakistan"},"image":{"@id":"https:\/\/leadpakistan.com.pk\/news\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/DailyLeadPak\/","https:\/\/x.com\/DailyLeadPak","https:\/\/instagram.com\/DailyLeadPak\/"]},{"@type":"Person","@id":"https:\/\/leadpakistan.com.pk\/news\/#\/schema\/person\/6ef8309590ff620a99ce35559f54fd62","name":"Web Desk","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/41f05ebf0a510062a26cf1d9e662155a6901c6733aa66a6c0f61daea3d680dc7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/41f05ebf0a510062a26cf1d9e662155a6901c6733aa66a6c0f61daea3d680dc7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/41f05ebf0a510062a26cf1d9e662155a6901c6733aa66a6c0f61daea3d680dc7?s=96&d=mm&r=g","caption":"Web Desk"},"url":"https:\/\/leadpakistan.com.pk\/news\/author\/edt\/"}]}},"_links":{"self":[{"href":"https:\/\/leadpakistan.com.pk\/news\/wp-json\/wp\/v2\/posts\/556388","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/leadpakistan.com.pk\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/leadpakistan.com.pk\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/leadpakistan.com.pk\/news\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/leadpakistan.com.pk\/news\/wp-json\/wp\/v2\/comments?post=556388"}],"version-history":[{"count":1,"href":"https:\/\/leadpakistan.com.pk\/news\/wp-json\/wp\/v2\/posts\/556388\/revisions"}],"predecessor-version":[{"id":556401,"href":"https:\/\/leadpakistan.com.pk\/news\/wp-json\/wp\/v2\/posts\/556388\/revisions\/556401"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/leadpakistan.com.pk\/news\/wp-json\/wp\/v2\/media\/556400"}],"wp:attachment":[{"href":"https:\/\/leadpakistan.com.pk\/news\/wp-json\/wp\/v2\/media?parent=556388"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/leadpakistan.com.pk\/news\/wp-json\/wp\/v2\/categories?post=556388"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/leadpakistan.com.pk\/news\/wp-json\/wp\/v2\/tags?post=556388"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}