{"id":2049,"count":2,"description":"","link":"https:\/\/leadpakistan.com.pk\/news\/tag\/sewerage\/","name":"sewerage","slug":"sewerage","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>sewerage Archives - Daily Lead Pakistan<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/leadpakistan.com.pk\/news\/tag\/sewerage\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"sewerage Archives - Daily Lead Pakistan\" \/>\n<meta property=\"og:url\" content=\"https:\/\/leadpakistan.com.pk\/news\/tag\/sewerage\/\" \/>\n<meta property=\"og:site_name\" content=\"Daily Lead Pakistan\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@DailyLeadPak\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/leadpakistan.com.pk\\\/news\\\/tag\\\/sewerage\\\/\",\"url\":\"https:\\\/\\\/leadpakistan.com.pk\\\/news\\\/tag\\\/sewerage\\\/\",\"name\":\"sewerage Archives - Daily Lead Pakistan\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/leadpakistan.com.pk\\\/news\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/leadpakistan.com.pk\\\/news\\\/tag\\\/sewerage\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/leadpakistan.com.pk\\\/news\\\/tag\\\/sewerage\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/leadpakistan.com.pk\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"sewerage\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/leadpakistan.com.pk\\\/news\\\/#website\",\"url\":\"https:\\\/\\\/leadpakistan.com.pk\\\/news\\\/\",\"name\":\"Daily Lead Pakistan\",\"description\":\"Daily Lead Pakistan\",\"publisher\":{\"@id\":\"https:\\\/\\\/leadpakistan.com.pk\\\/news\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/leadpakistan.com.pk\\\/news\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/leadpakistan.com.pk\\\/news\\\/#organization\",\"name\":\"Daily lead Pakistan\",\"url\":\"https:\\\/\\\/leadpakistan.com.pk\\\/news\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/leadpakistan.com.pk\\\/news\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/leadpakistan.com.pk\\\/news\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/logo3.jpg\",\"contentUrl\":\"https:\\\/\\\/leadpakistan.com.pk\\\/news\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/logo3.jpg\",\"width\":1000,\"height\":154,\"caption\":\"Daily lead Pakistan\"},\"image\":{\"@id\":\"https:\\\/\\\/leadpakistan.com.pk\\\/news\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/DailyLeadPak\\\/\",\"https:\\\/\\\/x.com\\\/DailyLeadPak\",\"https:\\\/\\\/instagram.com\\\/DailyLeadPak\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"sewerage Archives - Daily Lead Pakistan","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/leadpakistan.com.pk\/news\/tag\/sewerage\/","og_locale":"en_US","og_type":"article","og_title":"sewerage Archives - Daily Lead Pakistan","og_url":"https:\/\/leadpakistan.com.pk\/news\/tag\/sewerage\/","og_site_name":"Daily Lead Pakistan","twitter_card":"summary_large_image","twitter_site":"@DailyLeadPak","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/leadpakistan.com.pk\/news\/tag\/sewerage\/","url":"https:\/\/leadpakistan.com.pk\/news\/tag\/sewerage\/","name":"sewerage Archives - Daily Lead Pakistan","isPartOf":{"@id":"https:\/\/leadpakistan.com.pk\/news\/#website"},"breadcrumb":{"@id":"https:\/\/leadpakistan.com.pk\/news\/tag\/sewerage\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/leadpakistan.com.pk\/news\/tag\/sewerage\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/leadpakistan.com.pk\/news\/"},{"@type":"ListItem","position":2,"name":"sewerage"}]},{"@type":"WebSite","@id":"https:\/\/leadpakistan.com.pk\/news\/#website","url":"https:\/\/leadpakistan.com.pk\/news\/","name":"Daily Lead Pakistan","description":"Daily Lead Pakistan","publisher":{"@id":"https:\/\/leadpakistan.com.pk\/news\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/leadpakistan.com.pk\/news\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/leadpakistan.com.pk\/news\/#organization","name":"Daily lead Pakistan","url":"https:\/\/leadpakistan.com.pk\/news\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/leadpakistan.com.pk\/news\/#\/schema\/logo\/image\/","url":"https:\/\/leadpakistan.com.pk\/news\/wp-content\/uploads\/2022\/04\/logo3.jpg","contentUrl":"https:\/\/leadpakistan.com.pk\/news\/wp-content\/uploads\/2022\/04\/logo3.jpg","width":1000,"height":154,"caption":"Daily lead Pakistan"},"image":{"@id":"https:\/\/leadpakistan.com.pk\/news\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/DailyLeadPak\/","https:\/\/x.com\/DailyLeadPak","https:\/\/instagram.com\/DailyLeadPak\/"]}]}},"_links":{"self":[{"href":"https:\/\/leadpakistan.com.pk\/news\/wp-json\/wp\/v2\/tags\/2049","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/leadpakistan.com.pk\/news\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/leadpakistan.com.pk\/news\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/leadpakistan.com.pk\/news\/wp-json\/wp\/v2\/posts?tags=2049"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}